{"id":19320,"date":"2022-04-15T11:00:31","date_gmt":"2022-04-15T10:00:31","guid":{"rendered":"https:\/\/hugocardoso.com\/blog\/?p=19320"},"modified":"2025-07-01T10:25:18","modified_gmt":"2025-07-01T09:25:18","slug":"hulk-and-the-agents-of-s-m-a-s-h-t-1","status":"publish","type":"post","link":"https:\/\/hugocardoso.com\/blog\/archives\/19320","title":{"rendered":"Hulk and the Agents of S.M.A.S.H. T.1"},"content":{"rendered":"<p>Ao longo de duas temporadas vamos acompanhar e conhecer em detalhe a din\u00e2mica da equipa SMASH (Supreme Military Agency of Super Humans), que \u00e9 composta por Hulk, A-Bomb, She-Hulk, Skaar e Red Hulk. H\u00e1 uma elevada componente humor\u00edstica, aliada a um cen\u00e1rio de reality show, em que os her\u00f3is partilham pontos de vista e estados de humor, com base no que vai ocorrendo ao longo dos epis\u00f3dios.<\/p>\n<p>O vil\u00e3o \u00e9 The Leader, que pretende demonstrar que a equipa SMASH \u00e9 composta por monstros, de forma a ser visto como o salvador da Humanidade. Os dois epis\u00f3dios iniciais lan\u00e7am a g\u00e9nese da cria\u00e7\u00e3o da equipa, ap\u00f3s um ataque de Annihilus e da sua horda da Negative Zone.<\/p>\n<p>A partir desse momento, a narrativa assenta na necessidade de proteger Vista Verde, a isolada cidade no meio do deserto, que acolheu Hulk ap\u00f3s o incidente com a radia\u00e7\u00e3o gama. \u00c9 inevit\u00e1vel o cameo de Stan Lee, que \u00e9 o Presidente da C\u00e2mara, originando algumas intera\u00e7\u00f5es repletas de humor.<\/p>\n<p>Esta primeira temporada integra aventuras em que os nossos her\u00f3is ter\u00e3o de superar advers\u00e1rios como\u00a0The Collector, Ego The Living Planet, The Frost Giants, The Absorbing Man, Galactus, Doctor Doom, Sauron, The Impossible Man e Abomination. Conforme referido no in\u00edcio deste artigo, a narrativa tenta ser leve, com uma forte componente humor\u00edstica, o que nem sempre apresenta a melhor solu\u00e7\u00e3o.<\/p>\n<p>No que diz respeito a parcerias com outros her\u00f3is, temos a inclus\u00e3o do Fantastic Four, Guardians of the Galaxy, Thor, Doctor Strange e Spider-Man, com a devida correla\u00e7\u00e3o a Venom.<\/p>\n<p>Pessoalmente, prefiro o tom dos \u00faltimos epis\u00f3dios, em que o arco narrativo \u00e9 mais s\u00e9rio, focando-se na invas\u00e3o Skrull. Gostei particularmente da inclus\u00e3o de\u00a0Deathlok e Super Skrull , assim como a premissa criada para a segunda temporada, que assenta numa aventura c\u00f3smica, onde ser\u00e3o recriadas algumas das minhas hist\u00f3rias preferidas da Marvel, no que diz respeito a Hulk.<\/p>\n<p>Para concluir, \u00a0real\u00e7o o ponto mais forte desta s\u00e9rie, \u00a0com um incr\u00edvel elenco de vozes, tais como Fred Tatasciore, Seth Green, Eliza Dushku, Clancy Brown e James Arnold Taylor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao longo de duas temporadas vamos acompanhar e conhecer em detalhe a din\u00e2mica da equipa SMASH (Supreme Military Agency of Super Humans), que \u00e9 composta por Hulk, A-Bomb, She-Hulk, Skaar e Red Hulk. H\u00e1 uma elevada componente humor\u00edstica, aliada a &hellip; <a href=\"https:\/\/hugocardoso.com\/blog\/archives\/19320\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":19339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3136],"tags":[835,2575,2574],"class_list":["post-19320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-series","tag-hulk","tag-she-hulk","tag-smash"],"views":425,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/hugocardoso.com\/blog\/wp-content\/uploads\/2022\/04\/Hulk-AoS.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/posts\/19320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/comments?post=19320"}],"version-history":[{"count":1,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/posts\/19320\/revisions"}],"predecessor-version":[{"id":24914,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/posts\/19320\/revisions\/24914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/media\/19339"}],"wp:attachment":[{"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/media?parent=19320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/categories?post=19320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hugocardoso.com\/blog\/wp-json\/wp\/v2\/tags?post=19320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}